{"id":560,"date":"2014-06-23T20:25:43","date_gmt":"2014-06-23T20:25:43","guid":{"rendered":"https:\/\/learningtree.wsihosts.com\/?page_id=560"},"modified":"2025-08-29T11:13:57","modified_gmt":"2025-08-29T15:13:57","slug":"programme-garderie-educative","status":"publish","type":"page","link":"https:\/\/thelearningtree.ca\/fr\/programme-garderie-educative\/","title":{"rendered":"Notre programme de garderie \u00e9ducative et de pr\u00e9maternelle"},"content":{"rendered":"<p>Situ\u00e9 \u00e0 Dollard-des-Ormeaux, dans l\u2019Ouest-de-l\u2019\u00eele, L&#8217;Arbre de Connaissance a le plaisir de proposer des programmes de garderie \u00e9ducative et de pr\u00e9maternelle diversifi\u00e9s et bilingues, adapt\u00e9s \u00e0 chaque \u00e9tape du d\u00e9veloppement de votre enfant, de la petite enfance \u00e0 l\u2019\u00e9cole maternelle. Profitez d&#8217;un m\u00e9lange parfait de croissance acad\u00e9mique, d&#8217;activit\u00e9s enrichies et d&#8217;\u00e9v\u00e9nements sp\u00e9ciaux, garantissant un environnement \u00e9ducatif et stimulant complet pour votre enfant.<\/p>\n<p><a href=\"https:\/\/thelearningtree.ca\/fr\/nous-joindre\/prevoyez-une-visite\/\" target=\"\" rel=\"noopener noreferrer\"><button>Contactez-nous pour planifier une visite<\/button><\/a><\/p>\n<p><div class='content-column one_third'><div style=\"padding-right:25px;\"><div class='content-column full_width'><img decoding=\"async\" class=\"alignleft wp-image-886 size-full\" src=\"https:\/\/thelearningtree.ca\/wp-content\/uploads\/2014\/07\/infant.png\" alt=\"programme de garderie \u00e9ducative - b\u00e9b\u00e9s\" width=\"160\" height=\"113\" \/><\/div> <div class='content-column full_width'><h3 style=\"margin-top:20px;\" class=\"enrichedboxtext2\"><a href=\"https:\/\/thelearningtree.ca\/fr\/programme-garderie-educative\/poupons\/\">Curriculum pouponni\u00e8re<\/a><\/h3>\n<p>Notre <a href=\"https:\/\/thelearningtree.ca\/fr\/programme-garderie-educative\/poupons\/\">programme pour poupons<\/a> est con\u00e7u pour \u00eatre en phase avec les habitudes et les routines uniques de votre enfant. Nous travaillons avec vous pour veiller \u00e0 ce que votre enfant re\u00e7oive les soins et l&#8217;attention personnalis\u00e9s dont il a besoin.<br \/>\n<a style=\"padding-top: 10px; position: absolute;\" href=\"https:\/\/thelearningtree.ca\/fr\/programme-garderie-educative\/poupons\/\">Voir notre curriculum pour poupons<\/a>.<\/div><\/div><\/div><div class='content-column one_third'><div style=\"padding-right:25px;\"><div class='content-column full_width'><img decoding=\"async\" width=\"160\" height=\"113\" class=\"alignleft size-full wp-image-892\" src=\"\/wp-content\/uploads\/2014\/07\/toddler.png\" alt=\"toddler\" \/><\/div><div class='content-column full_width'><\/p>\n<h3 class=\"enrichedboxtext2\"><a href=\"https:\/\/thelearningtree.ca\/fr\/programme-garderie-educative\/bambins\/\">Curriculum bambins Junior et S\u00e9nior<\/a><\/h3>\n<p>Le programme des bambins Junior et S\u00e9nior est sp\u00e9cifiquement con\u00e7u pour aider les bambins \u00e0 acqu\u00e9rir la confiance et le contr\u00f4le de leurs \u00e9motions ainsi que d\u2019acqu\u00e9rir des comp\u00e9tences dans le langage \/ communication tout en explorant son environnement.<br \/>\n<a style=\"padding-top: 10px; position: absolute;\" href=\"https:\/\/thelearningtree.ca\/fr\/programme-garderie-educative\/bambins\/\">Voir notre curriculum pour bambins<\/a>.<\/div><\/div><\/div><div class='content-column one_third last_column'><div style=\"padding-right:25px;\"><div class='content-column full_width'><img decoding=\"async\" class=\"alignleft wp-image-889 size-full\" src=\"https:\/\/thelearningtree.ca\/wp-content\/uploads\/2014\/07\/preschool.png\" alt=\"programme de garderie \u00e9ducative\" width=\"160\" height=\"113\" \/><\/div><div class='content-column full_width'><\/p>\n<h3 class=\"enrichedboxtext2\"><a href=\"https:\/\/thelearningtree.ca\/fr\/prematernelle-privee\/\">Curriculum pr\u00e9maternelle<\/a><\/h3>\n<p>Notre programme bilingue de pr\u00e9maternelle priv\u00e9e junior (3-4 ans) est divis\u00e9 en unit\u00e9s th\u00e9matiques qui englobent une grande vari\u00e9t\u00e9 de sujets d&#8217;int\u00e9r\u00eat, tandis que notre programme s\u00e9nior (4-5 ans) offre une pr\u00e9paration compl\u00e8te \u00e0 la scolarisation formelle.<br \/>\n<a style=\"padding-top: 10px; position: absolute;\" href=\"https:\/\/thelearningtree.ca\/fr\/prematernelle-privee\/\">Voir notre curriculum de pr\u00e9maternelle<\/a>.<\/div><br \/><\/div><\/div><div class='clear_column'><\/div><\/p>\n<div class='content-column one_third'><div style=\"padding-right:25px;\"><p><div class='content-column full_width'><img decoding=\"async\" class=\"alignleft size-full wp-image-885\" src=\"\/wp-content\/uploads\/2014\/07\/enriched.png\" alt=\"enriched\" width=\"160\" height=\"113\" \/><\/div><div class='content-column full_width'><h3 class=\"enrichedboxtext2\"><a href=\"https:\/\/thelearningtree.ca\/fr\/programme-garderie-educative\/activites-enrichies\/\">Activit\u00e9 enrichies<\/a><\/h3>\n<p>Nos activit\u00e9s incluent la musique, le conte, le yoga, l\u2019informatique, la gymnastique, la danse et l\u2019art dramatique.<br \/>\n<a style=\"padding-top: 10px; position: absolute;\" href=\"https:\/\/thelearningtree.ca\/fr\/programme-garderie-educative\/activites-enrichies\/\">D\u00e9couvrir nos activit\u00e9s enrichies<\/a>.<\/div><br \/><\/div><\/div><div class='content-column one_third last_column'><div style=\"padding-right:25px;\"><div class='content-column full_width'><img decoding=\"async\" class=\"alignleft size-full wp-image-890\" src=\"\/wp-content\/uploads\/2014\/07\/specialevents.png\" alt=\"specialevents\" width=\"160\" height=\"113\" \/><\/div><div class='content-column full_width'><h3 class=\"enrichedboxtext2\"><a href=\"https:\/\/thelearningtree.ca\/fr\/programme-garderie-educative\/evenements-speciaux\/\">\u00c9v\u00e9nements sp\u00e9ciaux<\/a><\/h3>\n<p>Nos \u00e9v\u00e9nements sp\u00e9ciaux comprennent un d\u00eener de l\u2019Action de Gr\u00e2ce, une f\u00eate d&#8217;Halloween, une journ\u00e9e des grands-parents, un d\u00eener et une f\u00eate de No\u00ebl, un carnaval d&#8217;hiver, une c\u00e9r\u00e9monie sp\u00e9ciale de remise des dipl\u00f4mes, des r\u00e9citals de danse, une semaine multiculturelle et bien plus encore !<br \/>\n<a style=\"padding-top: 10px; position: absolute;\" href=\"https:\/\/thelearningtree.ca\/fr\/programme-garderie-educative\/evenements-speciaux\/\">D\u00e9couvrir nos \u00e9v\u00e9nements<\/a>.<br \/><\/div><br \/><\/div><\/div><div class='clear_column'><\/div><\/p>\n<p>&nbsp;<\/p>\n<h2>Nous acceptons les inscriptions \u00e0 <strong>temps partiel<\/strong> et \u00e0 <strong>temps plein<\/strong><\/h3>\n<p><a href=\"https:\/\/thelearningtree.ca\/fr\/nous-joindre\/\" target=\"\" rel=\"noopener noreferrer\"><button>Inscrivez votre enfant d\u00e8s aujourd\u2019hui!<\/button><\/a><\/p>\n<hr \/>\n<h2>Les 5 principes de notre programme<\/h2>\n<p>Notre programme de garde \u00e9ducative priv\u00e9e est bas\u00e9 sur 5 principes fondamentaux :<\/p>\n<ol>\n<li><strong>Valoriser l&#8217;unicit\u00e9:<\/strong> Chaque enfant est unique. Nos activit\u00e9s \u00e9ducatives sont con\u00e7ues pour r\u00e9pondre aux besoins uniques, aux passions et au rythme de croissance de votre enfant.<\/li>\n<li><strong>Guider et soutenir:<\/strong> Les enfants sont les principaux acteurs de leur propre d\u00e9veloppement. Leur croissance d\u00e9pend de leurs capacit\u00e9s individuelles et de leurs motivations. Dans ce contexte, l&#8217;adulte joue le r\u00f4le de guide et de soutien, aidant l&#8217;enfant \u00e0 devenir ind\u00e9pendant.<\/li>\n<li><strong>Cultiver une d\u00e9marche compl\u00e8te.<\/strong> La croissance holistique d\u00e9finit le d\u00e9veloppement d&#8217;un enfant. Notre programme \u00e9ducatif couvre plusieurs facettes : \u00e9motionnelle, physique, sociale et \u00e9thique, cognitive et linguistique.<\/li>\n<li><strong>Promouvoir le jeu:<\/strong> Les enfants apprennent en jouant. Dans le cadre de nos services d\u00e9di\u00e9s \u00e0 la petite enfance, le jeu n&#8217;est pas seulement l&#8217;objectif principal, mais aussi le fondement de notre strat\u00e9gie \u00e9ducative.<\/li>\n<li><strong>Encourager une approche collaborative:<\/strong> Un partenariat sans faille entre nous et vous, les parents, est essentiel au d\u00e9veloppement \u00e9quilibr\u00e9 de votre enfant.<\/li>\n<\/ol>\n<hr \/>\n<h2>Les 6 piliers d&#8217;apprentissage de notre programme de garderie \u00e9ducative<\/h2>\n<p><div class='content-column one_third'><div style=\"padding-right:25px;\"><div class='content-column full_width'><\/div> <div class='content-column full_width'><img decoding=\"async\" src=\"https:\/\/thelearningtree.ca\/wp-content\/uploads\/2025\/08\/LearningTree_Pillars_Icons_01_PhysicalSkills.png\" alt=\"Habilet\u00e9s physiques icon\" height=\"120px\" width=\"120px\" class=\"mobile-image\"\/><\/p>\n<h3>Habilet\u00e9s physiques<\/h3>\n<p>Nous nous concentrons sur l&#8217;am\u00e9lioration des capacit\u00e9s motrices, en veillant \u00e0 ce que les enfants d\u00e9veloppent \u00e0 la fois les comp\u00e9tences motrices fines et globales. Les activit\u00e9s comprennent des t\u00e2ches pratiques et des jeux physiques qui favorisent l&#8217;agilit\u00e9 et la force.<br \/><\/div><br \/><\/div><\/div><div class='content-column one_third'><div style=\"padding-right:25px;\"><div class='content-column full_width'><\/div><div class='content-column full_width'><img decoding=\"async\" src=\"https:\/\/thelearningtree.ca\/wp-content\/uploads\/2025\/08\/LearningTree_Pillars_Icons_02_Social.png\" alt=\"Aptitudes de socialisation icon\" height=\"120px\" width=\"120px\" class=\"mobile-image\"\/><\/p>\n<h3>Aptitudes de socialisation<\/h3>\n<p>En encourageant les interactions et les activit\u00e9s de groupe, nous aidons les enfants \u00e0 construire des comp\u00e9tences interpersonnelles essentielles, \u00e0 comprendre les signaux sociaux et \u00e0 nouer des amiti\u00e9s. Le tout dans le but de former des individus confiants et coop\u00e9ratifs.<br \/><\/div><br \/><\/div><\/div><div class='content-column one_third last_column'><div style=\"padding-right:25px;\"><div class='content-column full_width'><\/div><div class='content-column full_width'><img decoding=\"async\" src=\"https:\/\/thelearningtree.ca\/wp-content\/uploads\/2025\/08\/LearningTree_Pillars_Icons_03_Language.png\" alt=\"Comp\u00e9tences linguistiques icon\" height=\"120px\" width=\"120px\" class=\"mobile-image\"\/><\/p>\n<h3>Comp\u00e9tences linguistiques<\/h3>\n<p>Notre programme d&#8217;\u00e9tudes initie les enfants aux nuances du langage et \u00e0 la communication efficace. \u00c0 travers des histoires, des conversations et des sessions interactives, ils affinent leur expression verbale et \u00e9crite.<br \/><\/div><br \/><\/div><\/div><div class='clear_column'><\/div><\/p>\n<p><div class='content-column one_third'><div style=\"padding-right:25px;\"><div class='content-column full_width'><\/div> <div class='content-column full_width'><img decoding=\"async\" src=\"https:\/\/thelearningtree.ca\/wp-content\/uploads\/2025\/08\/LearningTree_Pillars_Icons_04_Cognitive.png\" alt=\"Capacit\u00e9s cognitives icon\" height=\"120px\" width=\"120px\" class=\"mobile-image\"\/><\/p>\n<h3>Capacit\u00e9s cognitives<\/h3>\n<p>Nous stimulons les jeunes esprits avec des t\u00e2ches de r\u00e9solution de probl\u00e8mes et des activit\u00e9s de raisonnement logique. Cette approche aiguise leur pens\u00e9e analytique et les pr\u00e9pare aux d\u00e9fis acad\u00e9miques \u00e0 venir.<\/p><\/div><br \/><\/div><\/div><div class='content-column one_third'><div style=\"padding-right:25px;\"><div class='content-column full_width'><\/div><div class='content-column full_width'><img decoding=\"async\" src=\"https:\/\/thelearningtree.ca\/wp-content\/uploads\/2025\/08\/LearningTree_Pillars_Icons_05_Emotional.png\" alt=\"Comp\u00e9tences \u00e9motionnelles icon\" height=\"120px\" width=\"120px\" class=\"mobile-image\"\/><\/p>\n<h3>Comp\u00e9tences \u00e9motionnelles<\/h3>\n<p>Reconna\u00eetre et g\u00e9rer ses \u00e9motions est vital. Nous cr\u00e9ons des espaces s\u00fbrs pour que les enfants puissent exprimer leurs sentiments, comprendre l&#8217;empathie et d\u00e9velopper leur r\u00e9silience, les guidant ainsi vers la maturit\u00e9 \u00e9motionnelle.<br \/><\/div><br \/><\/div><\/div><div class='content-column one_third last_column'><div style=\"padding-right:25px;\"><div class='content-column full_width'><\/div><div class='content-column full_width'><img decoding=\"async\" src=\"https:\/\/thelearningtree.ca\/wp-content\/uploads\/2025\/08\/LearningTree_Pillars_Icons_06_Artistic.png\" alt=\"Comp\u00e9tences artistiques icon\" height=\"120px\" width=\"120px\" class=\"mobile-image\"\/><\/p>\n<h3>Comp\u00e9tences artistiques<\/h3>\n<p>Nous encourageons la cr\u00e9ativit\u00e9 en initiant les enfants \u00e0 diverses formes d&#8217;art. Gr\u00e2ce \u00e0 la peinture, \u00e0 la musique et au th\u00e9\u00e2tre, ils lib\u00e8rent leur imagination et appr\u00e9cient la beaut\u00e9 de l&#8217;expression.<br \/><\/div><br \/><\/div><\/div><div class='clear_column'><\/div><\/p>\n<p>Si vous souhaitez obtenir de plus amples informations sur notre programme de garderie \u00e9ducative exceptionnel et notre <a href=\"https:\/\/thelearningtree.ca\/fr\/prematernelle-privee\/\">programme pr\u00e9scolaire priv\u00e9<\/a> in\u00e9gal\u00e9, veuillez nous contacter. Les sections suivantes peuvent \u00e9galement apporter des r\u00e9ponses \u00e0 nombre de vos questions : <a href=\"https:\/\/thelearningtree.ca\/fr\/garderie-privee-non-subventionnee\/\">A propos de nous<\/a>, <a href=\"https:\/\/thelearningtree.ca\/fr\/nos-installations\/\">Nos installations<\/a> et <a href=\"https:\/\/thelearningtree.ca\/fr\/droits-de-scolarite-tout-inclus\/\">Droits de scolarit\u00e9 tout inclus<\/a>.<\/p>\n<p><a href=\"https:\/\/thelearningtree.ca\/fr\/nous-joindre\/\"><button>Nous joindre<\/button><\/a><\/p>\n<h2>FAQ sur notre programme \u00e9ducatif<\/h2>\n<div id=\"rank-math-rich-snippet-wrapper\"><div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-1\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">Quelle est votre approche p\u00e9dagogique et comment soutient-elle chaque \u00e9tape du d\u00e9veloppement de mon enfant ?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Nous suivons une philosophie holistique et centr\u00e9e sur l'enfant qui favorise le d\u00e9veloppement physique, \u00e9motionnel, cognitif et social gr\u00e2ce \u00e0 des jeux guid\u00e9s et un apprentissage th\u00e9matique.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-2\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">Comment adaptez-vous votre programme aux diff\u00e9rents groupes d'\u00e2ge, des nourrissons aux enfants d'\u00e2ge pr\u00e9scolaire ?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Nos programmes sont adapt\u00e9s aux besoins de d\u00e9veloppement de chaque groupe d'\u00e2ge, notamment les soins personnalis\u00e9s pour les nourrissons, les comp\u00e9tences \u00e9motionnelles et de communication pour les tout-petits et la pr\u00e9paration \u00e0 l'\u00e9cole pour les enfants d'\u00e2ge pr\u00e9scolaire.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-3\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">Votre programme de garderie est-il bilingue ?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Oui, nous offrons un environnement d'apprentissage bilingue qui initie en douceur les enfants \u00e0 l'anglais et au fran\u00e7ais par le biais de contes, de jeux et d'activit\u00e9s structur\u00e9es.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-4\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u00c0 quelle fr\u00e9quence mettez-vous \u00e0 jour ou r\u00e9visez-vous votre programme ?<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Notre programme est r\u00e9guli\u00e8rement r\u00e9vis\u00e9 par nos \u00e9ducateurs exp\u00e9riment\u00e9s afin de s'assurer qu'il est conforme aux meilleures pratiques actuelles en mati\u00e8re d'\u00e9ducation de la petite enfance et qu'il r\u00e9pond aux besoins \u00e9volutifs de nos enfants.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Situ\u00e9 \u00e0 Dollard-des-Ormeaux, dans l\u2019Ouest-de-l\u2019\u00eele, L&#8217;Arbre de Connaissance a le plaisir de proposer des programmes de garderie \u00e9ducative et de pr\u00e9maternelle diversifi\u00e9s et bilingues, adapt\u00e9s \u00e0 chaque \u00e9tape du d\u00e9veloppement de votre enfant, de la petite enfance \u00e0 l\u2019\u00e9cole maternelle. Profitez d&#8217;un m\u00e9lange parfait de croissance acad\u00e9mique, d&#8217;activit\u00e9s enrichies et d&#8217;\u00e9v\u00e9nements sp\u00e9ciaux, garantissant un environnement [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-560","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"thelearningtree.ca","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"The featured image should be at least 200 by 200 pixels to be picked up by Facebook and other social media sites.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"programme-garderie-educative","permalinkFormat":"https:\/\/thelearningtree.ca\/fr\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/thelearningtree.ca\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":false,"primaryTaxonomy":false,"serpData":{"title":"Programme de garderie \u00e9ducative de L'Arbre de Connaissance","description":"D\u00e9couvrez le programme enrichi et \u00e9ducatif de la garderie L'Arbre de Connaissance, une garderie priv\u00e9e situ\u00e9e \u00e0 l'ouest de l'\u00eele de Montr\u00e9al.","focusKeywords":"programme de garderie \u00e9ducative","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"username","primaryTerm":0,"authorName":"admin","titleTemplate":"%title% %page% %sep% %sitename%","descriptionTemplate":"%title% %excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["absolument","amazement","astonishing","authentique","beau","bien-\u00eatre","brillant","captivant","charismatique","choc","clair","compl\u00e8tement","confidentiel","confiance","cons\u00e9quent","cr\u00e9atif","d\u00e9finitivement","d\u00e9licieux","d\u00e9montrer","d\u00e9p\u00eachez-vous","d\u00e9termin\u00e9","digne","dynamique","\u00e9blouissant","\u00e9clatant","\u00e9conomique","\u00e9fficace","\u00e9l\u00e9gant","\u00e9motionnel","\u00e9nergique","\u00e9norme","\u00e9poustouflant","essentiel","\u00e9tonnant","exclusif","exp\u00e9rience","fabuleux","fantastique","formidable","fort","garanti","g\u00e9ant","g\u00e9n\u00e9reux","grandiose","gratuit","habile","harmonieux","historique","hors pair","important","incroyable","indispensable","inoubliable","inspirant","innovant","intense","invention","irr\u00e9sistible","l\u00e9gendaire","lumineux","luxe","magique","magnifique","majestueux","marquant","merveilleux","miraculeux","motivant","n\u00e9cessaire","nouvelle","officiel","parfait","passionn\u00e9","persuasif","ph\u00e9nom\u00e9nal","plaisir","populaire","pouvoir","prestigieux","prodigieux","profond","prosp\u00e8re","puissant","qualit\u00e9","radieux","rapide","r\u00e9ussi","r\u00e9volutionnaire","satisfait","s\u00e9curit\u00e9","sensationnel","serein","somptueux","splendide","sublime","surprenant","talentueux","terrifiant","unique","valeur","vibrant","victorieux","vif","vraiment","z\u00e9l\u00e9"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":true},"homeUrl":"https:\/\/thelearningtree.ca\/fr\/","objectID":560,"objectType":"post","locale":"fr","localeFull":"fr_FR","overlayImages":{"play":{"name":"Play icon","url":"https:\/\/thelearningtree.ca\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/vhosts\/thelearningtree.ca\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF icon","url":"https:\/\/thelearningtree.ca\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/vhosts\/thelearningtree.ca\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/thelearningtree.ca\/wp-content\/uploads\/2016\/06\/Library-copy.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fthelearningtree.ca%2Ffr%2F&r=https%3A%2F%2Fthelearningtree.ca%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fpages%2F560%3Fnonce%3Dc94aef7bdb&pro=1","maxTags":100,"trendsIcon":"<svg width=\"100%\" height=\"100%\" viewBox=\"0 0 36 36\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" fit=\"\" preserveAspectRatio=\"xMidYMid meet\" focusable=\"false\">\n\t\t<g id=\"Page-1\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t<g id=\"Trends-Arrow\">\n\t\t\t\t<g id=\"TrendsArrow\">\n\t\t\t\t\t<path d=\"M1.11227159,26.3181534 L10.2875029,17.1429221 L13.7152617,20.5706809 L4.5400304,29.7459122 C4.20518633,30.0807563 3.66229681,30.0807562 3.32745277,29.7459122 L1.11136262,27.529822 C0.776518575,27.194978 0.776518548,26.6520885 1.11136262,26.3172444 L1.11227159,26.3181534 Z\" id=\"Shape\" fill=\"#4285F4\" fill-rule=\"nonzero\"><\/path>\n\t\t\t\t\t<path d=\"M14.3201543,14.3211528 L22.283717,22.2847155 L19.4658829,25.1025495 C19.1310388,25.4373936 18.5881494,25.4373937 18.2533053,25.1025495 L10.2906516,17.1398959 L13.1084857,14.3220618 C13.4429747,13.987572 13.9851638,13.9871653 14.3201543,14.3211528 Z\" id=\"Shape\" fill=\"#EA4335\" fill-rule=\"nonzero\"><\/path>\n\t\t\t\t\t<polygon id=\"Rectangle-path\" fill=\"#FABB05\" fill-rule=\"nonzero\" points=\"18.8573051 18.8577571 28.2843236 9.43073862 31.7120824 12.8584974 22.2850639 22.2855159\"><\/polygon>\n\t\t\t\t\t<path d=\"M35.0711567,15.5054713 L35.0711567,7 L35.0711567,7 C35.0711567,6.44771525 34.6234415,6 34.0711567,6 L25.5656854,6 L25.5656854,6 C25.0134007,6 24.5656854,6.44771525 24.5656854,7 C24.5656854,7.26521649 24.6710423,7.5195704 24.8585786,7.70710678 L33.3640499,16.2125781 L33.3640499,16.2125781 C33.7545742,16.6031024 34.3877392,16.6031024 34.7782635,16.2125781 C34.9657999,16.0250417 35.0711567,15.7706878 35.0711567,15.5054713 Z\" id=\"Shape\" fill=\"#34A853\" fill-rule=\"nonzero\"><\/path>\n\t\t\t\t\t<rect id=\"Rectangle-path\" x=\"0\" y=\"0\" width=\"36\" height=\"36\"><\/rect>\n\t\t\t\t<\/g>\n\t\t\t<\/g>\n\t\t<\/g>\n\t<\/svg>","showScore":true,"siteFavIcon":"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAQCAYAAAAf8\/9hAAABs0lEQVR4AWL4\/\/8\/RRjO8Iucx+noO0MWUDo16FYABMGP6ZfUcRnWtm27jVPbtm3bttuH2t3eFPcY9pLz7NxiLjCyVd87pKnHyqXyxtCs8APd0rnyxiu4qSeA3QEDrAwBDrT1s1Rc\/OrjLZwqVmOSu6+Lamcpp2KKMA9PH1BYXMe1mUP5qotvXTywsOEEYHXxrY+3cqk6TMkYpNr2FeoY3KIr0RPtn9wQ2unlA+GMkRw6+9TFw4YTwDUzx\/JVvARj9KaedXRO8P5B1Du2S32smzqUrcKGEyA+uAgQjKX7zf0boWHGfn71jIKj2689gxp7OAGShNcBUmLMPVjZuiKcA2vuWHHDCQxMCz629kXAIU4ApY15QwggAFbfOP9DhgBJ+nWVJ1AZAfICAj1pAlY6hCADZnveQf7bQIwzVONGJonhLIlS9gr5mFg44Xd+4S3XHoGNPdJl1INIwKyEgHckEhgTe1bGiFY9GSFBYUwLh1IkiJUbY407E7syBSFxKTszEoiE\/YdrgCEayDmtaJwCI9uu8TKMuZSVfSa4BpGgzvomBR\/INhLGzrqDotp01ZR8pn\/1L0JN9d9XNyx0AAAAAElFTkSuQmCC","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":true,"is_front_page":false,"trendsUpgradeLink":"https:\/\/thelearningtree.ca\/wp-admin\/admin.php?page=rank-math&view=help","trendsUpgradeLabel":"Activer maintenant","trendsPreviewImage":"https:\/\/thelearningtree.ca\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["absolument","amazement","astonishing","authentique","beau","bien-\u00eatre","brillant","captivant","charismatique","choc","clair","compl\u00e8tement","confidentiel","confiance","cons\u00e9quent","cr\u00e9atif","d\u00e9finitivement","d\u00e9licieux","d\u00e9montrer","d\u00e9p\u00eachez-vous","d\u00e9termin\u00e9","digne","dynamique","\u00e9blouissant","\u00e9clatant","\u00e9conomique","\u00e9fficace","\u00e9l\u00e9gant","\u00e9motionnel","\u00e9nergique","\u00e9norme","\u00e9poustouflant","essentiel","\u00e9tonnant","exclusif","exp\u00e9rience","fabuleux","fantastique","formidable","fort","garanti","g\u00e9ant","g\u00e9n\u00e9reux","grandiose","gratuit","habile","harmonieux","historique","hors pair","important","incroyable","indispensable","inoubliable","inspirant","innovant","intense","invention","irr\u00e9sistible","l\u00e9gendaire","lumineux","luxe","magique","magnifique","majestueux","marquant","merveilleux","miraculeux","motivant","n\u00e9cessaire","nouvelle","officiel","parfait","passionn\u00e9","persuasif","ph\u00e9nom\u00e9nal","plaisir","populaire","pouvoir","prestigieux","prodigieux","profond","prosp\u00e8re","puissant","qualit\u00e9","radieux","rapide","r\u00e9ussi","r\u00e9volutionnaire","satisfait","s\u00e9curit\u00e9","sensationnel","serein","somptueux","splendide","sublime","surprenant","talentueux","terrifiant","unique","valeur","vibrant","victorieux","vif","vraiment","z\u00e9l\u00e9"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"searchIntents":[],"isAnalyticsConnected":true,"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/thelearningtree.ca\/fr\/wp-json\/wp\/v2\/pages\/560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thelearningtree.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thelearningtree.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thelearningtree.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/thelearningtree.ca\/fr\/wp-json\/wp\/v2\/comments?post=560"}],"version-history":[{"count":16,"href":"https:\/\/thelearningtree.ca\/fr\/wp-json\/wp\/v2\/pages\/560\/revisions"}],"predecessor-version":[{"id":3972,"href":"https:\/\/thelearningtree.ca\/fr\/wp-json\/wp\/v2\/pages\/560\/revisions\/3972"}],"wp:attachment":[{"href":"https:\/\/thelearningtree.ca\/fr\/wp-json\/wp\/v2\/media?parent=560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}